{"id":3169,"date":"2022-04-11T17:59:30","date_gmt":"2022-04-11T15:59:30","guid":{"rendered":"https:\/\/giflex.it\/?p=3169"},"modified":"2022-04-12T17:23:12","modified_gmt":"2022-04-12T15:23:12","slug":"congresso-api-finalmente-ci-siamo","status":"publish","type":"post","link":"https:\/\/giflex.it\/en\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/","title":{"rendered":"Congresso API, finalmente ci siamo!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3176 alignleft\" src=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/04\/API-2022-800x1131-1.jpg\" alt=\"\" width=\"406\" height=\"574\" \/>Il 4\u00b0 Congresso Internazionale sull\u2019innovazione tecnologica nell\u2019industria dell\u2019imballaggio \u201cAdvances in the packaging Industry\u201d, torna di nuovo in presenza a Napoli, 24 e 25 Novembre 2022, presso il Museo Donnaregina.<\/p>\n<p>L\u2019evento sar\u00e0 presieduto da Domenico Acierno, in qualit\u00e0 di Presidente del Centro Regionale di Competenza Tecnologie e da Alberto Palaveri, Presidente di Giflex.<\/p>\n<p>Il congresso, organizzato in stretta collaborazione con il Consiglio Nazionale delle Ricerche, l\u2019Universit\u00e0 di Napoli Federico II, l\u2019Universit\u00e0 di Salerno unir\u00e0 il mondo accademico e della ricerca con quello industriale dell\u2019intera filiera dell\u2019imballaggio, dai produttori di materie prime agli utilizzatori finali.<\/p>\n<p>Un autorevole Comitato Scientifico sta lavorando alla stesura del programma che includer\u00e0 presentazioni dal mondo scientifico e industriale su tematiche classiche e\/o pi\u00f9 di rilievo in questo momento. Si considereranno tutti i materiali flessibili destinati all\u2019imballaggio con enfasi particolare dedicata a quelli di origine bio e\/o compostabili o riciclabili a fine vita. Ovviamente significativa attenzione verr\u00e0 data alle nuove tecnologie e\/o nuove applicazioni e a costruire uno \u201cspazio\u201d destinato alle nuove leve ed alle start-up innovative.<\/p>\n<p>E\u2019 prevista la partecipazione di circa 250 tra Docenti, Ricercatori e Rappresentanti del mondo industriale provenienti da tutto il mondo, che potranno godere delle bellezze della citt\u00e0 di Napoli e delle sue specialit\u00e0.<\/p>\n<p>Aperte le Call for papers: <a href=\"http:\/\/www.apicongress.it\">www.apicongress.it<\/a><\/p>\n<p><a href=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/04\/API-2022-call-for-abstracts.pdf\">Locandina API Congress<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 4\u00b0 Congresso Internazionale sull\u2019innovazione tecnologica nell\u2019industria dell\u2019imballaggio \u201cAdvances in the packaging Industry\u201d, torna di nuovo in presenza a Napoli, 24 e 25 Novembre 2022, presso il Museo Donnaregina. L\u2019evento sar\u00e0 presieduto da Domenico Acierno, in qualit\u00e0 di Presidente del Centro Regionale di Competenza Tecnologie e da Alberto Palaveri, Presidente di Giflex. Il congresso, organizzato [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":3068,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[11],"tags":[],"fonte":[],"posizione":[31,7],"class_list":["post-3169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","posizione-iniziative","posizione-news-giflex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Congresso API, finalmente ci siamo! - Giflex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congresso API, finalmente ci siamo! - Giflex\" \/>\n<meta property=\"og:description\" content=\"Il 4\u00b0 Congresso Internazionale sull\u2019innovazione tecnologica nell\u2019industria dell\u2019imballaggio \u201cAdvances in the packaging Industry\u201d, torna di nuovo in presenza a Napoli, 24 e 25 Novembre 2022, presso il Museo Donnaregina. L\u2019evento sar\u00e0 presieduto da Domenico Acierno, in qualit\u00e0 di Presidente del Centro Regionale di Competenza Tecnologie e da Alberto Palaveri, Presidente di Giflex. Il congresso, organizzato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/\" \/>\n<meta property=\"og:site_name\" content=\"Giflex\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-11T15:59:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-12T15:23:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/03\/Locandina-API.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"elena\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"elena\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/\"},\"author\":{\"name\":\"elena\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/41056efa2ab4cc1ae4953882b8ec42d6\"},\"headline\":\"Congresso API, finalmente ci siamo!\",\"datePublished\":\"2022-04-11T15:59:30+00:00\",\"dateModified\":\"2022-04-12T15:23:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/\"},\"wordCount\":225,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/Locandina-API.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/\",\"url\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/\",\"name\":\"Congresso API, finalmente ci siamo! - Giflex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/Locandina-API.png\",\"datePublished\":\"2022-04-11T15:59:30+00:00\",\"dateModified\":\"2022-04-12T15:23:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/41056efa2ab4cc1ae4953882b8ec42d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/Locandina-API.png\",\"contentUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/03\\\/Locandina-API.png\",\"width\":1081,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/04\\\/11\\\/congresso-api-finalmente-ci-siamo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giflex.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Congresso API, finalmente ci siamo!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\",\"url\":\"https:\\\/\\\/giflex.it\\\/\",\"name\":\"Giflex\",\"description\":\"Italian Flexible Packaging Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giflex.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/41056efa2ab4cc1ae4953882b8ec42d6\",\"name\":\"elena\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g\",\"caption\":\"elena\"},\"url\":\"https:\\\/\\\/giflex.it\\\/en\\\/author\\\/elena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Congresso API, finalmente ci siamo! - Giflex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/","og_locale":"en_US","og_type":"article","og_title":"Congresso API, finalmente ci siamo! - Giflex","og_description":"Il 4\u00b0 Congresso Internazionale sull\u2019innovazione tecnologica nell\u2019industria dell\u2019imballaggio \u201cAdvances in the packaging Industry\u201d, torna di nuovo in presenza a Napoli, 24 e 25 Novembre 2022, presso il Museo Donnaregina. L\u2019evento sar\u00e0 presieduto da Domenico Acierno, in qualit\u00e0 di Presidente del Centro Regionale di Competenza Tecnologie e da Alberto Palaveri, Presidente di Giflex. Il congresso, organizzato [&hellip;]","og_url":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/","og_site_name":"Giflex","article_published_time":"2022-04-11T15:59:30+00:00","article_modified_time":"2022-04-12T15:23:12+00:00","og_image":[{"width":1081,"height":620,"url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/03\/Locandina-API.png","type":"image\/png"}],"author":"elena","twitter_card":"summary_large_image","twitter_misc":{"Written by":"elena","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/#article","isPartOf":{"@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/"},"author":{"name":"elena","@id":"https:\/\/giflex.it\/#\/schema\/person\/41056efa2ab4cc1ae4953882b8ec42d6"},"headline":"Congresso API, finalmente ci siamo!","datePublished":"2022-04-11T15:59:30+00:00","dateModified":"2022-04-12T15:23:12+00:00","mainEntityOfPage":{"@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/"},"wordCount":225,"commentCount":0,"image":{"@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/03\/Locandina-API.png","articleSection":["Eventi"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/","url":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/","name":"Congresso API, finalmente ci siamo! - Giflex","isPartOf":{"@id":"https:\/\/giflex.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/#primaryimage"},"image":{"@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/03\/Locandina-API.png","datePublished":"2022-04-11T15:59:30+00:00","dateModified":"2022-04-12T15:23:12+00:00","author":{"@id":"https:\/\/giflex.it\/#\/schema\/person\/41056efa2ab4cc1ae4953882b8ec42d6"},"breadcrumb":{"@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/#primaryimage","url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/03\/Locandina-API.png","contentUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/03\/Locandina-API.png","width":1081,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/giflex.it\/2022\/04\/11\/congresso-api-finalmente-ci-siamo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giflex.it\/"},{"@type":"ListItem","position":2,"name":"Congresso API, finalmente ci siamo!"}]},{"@type":"WebSite","@id":"https:\/\/giflex.it\/#website","url":"https:\/\/giflex.it\/","name":"Giflex","description":"Italian Flexible Packaging Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giflex.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/giflex.it\/#\/schema\/person\/41056efa2ab4cc1ae4953882b8ec42d6","name":"elena","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g","caption":"elena"},"url":"https:\/\/giflex.it\/en\/author\/elena\/"}]}},"_links":{"self":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/3169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/comments?post=3169"}],"version-history":[{"count":3,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/3169\/revisions"}],"predecessor-version":[{"id":3179,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/3169\/revisions\/3179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media\/3068"}],"wp:attachment":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media?parent=3169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/categories?post=3169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/tags?post=3169"},{"taxonomy":"fonte","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/fonte?post=3169"},{"taxonomy":"posizione","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posizione?post=3169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}