{"id":3064,"date":"2022-03-10T09:50:21","date_gmt":"2022-03-10T08:50:21","guid":{"rendered":"https:\/\/giflex.it\/?p=3064"},"modified":"2022-03-10T09:50:21","modified_gmt":"2022-03-10T08:50:21","slug":"performance-ambientali-sotto-controllo-con-il-tool-fps","status":"publish","type":"post","link":"https:\/\/giflex.it\/en\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/","title":{"rendered":"Performance ambientali sotto controllo con il tool FpS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2999 alignleft\" src=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg\" alt=\"\" width=\"331\" height=\"192\" \/>\u00c8 stato presentato ufficialmente lo scorso 1\u00b0 marzo ed \u00e8 a disposizione anche delle aziende associate GIFLEX il tool sviluppato dalla Federazione Carta e Grafica per la Sostenibilit\u00e0.<\/p>\n<p>Il Progetto FpS \u00e8 una metodologia integrata \u2013 con un protocollo e un software \u2013 che rende possibile monitorare e rendicontare le performance ambientali, sociali ed economiche rispondendo ai principali standard internazionali e rispettando le linee di indirizzo delle pi\u00f9 autorevoli fonti, nazionali, europee e internazionali sui temi della sostenibilit\u00e0 e dell\u2019economia circolare, con una costante coerenza ai criteri della finanza sostenibile.<\/p>\n<p>Per saperne di pi\u00f9: <a href=\"https:\/\/giflex.it\/2022\/03\/01\/presentato-il-progetto-che-apre-la-sostenibilita-alle-aziende-della-filiera\/\" target=\"_blank\" rel=\"noopener\">leggi l&#8217;articolo.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 stato presentato ufficialmente lo scorso 1\u00b0 marzo ed \u00e8 a disposizione anche delle aziende associate GIFLEX il tool sviluppato dalla Federazione Carta e Grafica per la Sostenibilit\u00e0. Il Progetto FpS \u00e8 una metodologia integrata \u2013 con un protocollo e un software \u2013 che rende possibile monitorare e rendicontare le performance ambientali, sociali ed economiche [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":2999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[75],"tags":[],"fonte":[],"posizione":[7],"class_list":["post-3064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita","posizione-news-giflex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Performance ambientali sotto controllo con il tool FpS - Giflex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Performance ambientali sotto controllo con il tool FpS - Giflex\" \/>\n<meta property=\"og:description\" content=\"\u00c8 stato presentato ufficialmente lo scorso 1\u00b0 marzo ed \u00e8 a disposizione anche delle aziende associate GIFLEX il tool sviluppato dalla Federazione Carta e Grafica per la Sostenibilit\u00e0. Il Progetto FpS \u00e8 una metodologia integrata \u2013 con un protocollo e un software \u2013 che rende possibile monitorare e rendicontare le performance ambientali, sociali ed economiche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/\" \/>\n<meta property=\"og:site_name\" content=\"Giflex\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-10T08:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elena\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"elena\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/\"},\"author\":{\"name\":\"elena\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/41056efa2ab4cc1ae4953882b8ec42d6\"},\"headline\":\"Performance ambientali sotto controllo con il tool FpS\",\"datePublished\":\"2022-03-10T08:50:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/\"},\"wordCount\":100,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/02\\\/locandina_sostenibilita-scaled.jpg\",\"articleSection\":[\"Sostenibilit\u00e0\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/\",\"url\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/\",\"name\":\"Performance ambientali sotto controllo con il tool FpS - Giflex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/02\\\/locandina_sostenibilita-scaled.jpg\",\"datePublished\":\"2022-03-10T08:50:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/41056efa2ab4cc1ae4953882b8ec42d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/02\\\/locandina_sostenibilita-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/02\\\/locandina_sostenibilita-scaled.jpg\",\"width\":2560,\"height\":1486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/03\\\/10\\\/performance-ambientali-sotto-controllo-con-il-tool-fps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giflex.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Performance ambientali sotto controllo con il tool FpS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\",\"url\":\"https:\\\/\\\/giflex.it\\\/\",\"name\":\"Giflex\",\"description\":\"Italian Flexible Packaging Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giflex.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/41056efa2ab4cc1ae4953882b8ec42d6\",\"name\":\"elena\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g\",\"caption\":\"elena\"},\"url\":\"https:\\\/\\\/giflex.it\\\/en\\\/author\\\/elena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Performance ambientali sotto controllo con il tool FpS - Giflex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/","og_locale":"en_US","og_type":"article","og_title":"Performance ambientali sotto controllo con il tool FpS - Giflex","og_description":"\u00c8 stato presentato ufficialmente lo scorso 1\u00b0 marzo ed \u00e8 a disposizione anche delle aziende associate GIFLEX il tool sviluppato dalla Federazione Carta e Grafica per la Sostenibilit\u00e0. Il Progetto FpS \u00e8 una metodologia integrata \u2013 con un protocollo e un software \u2013 che rende possibile monitorare e rendicontare le performance ambientali, sociali ed economiche [&hellip;]","og_url":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/","og_site_name":"Giflex","article_published_time":"2022-03-10T08:50:21+00:00","og_image":[{"width":2560,"height":1486,"url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","type":"image\/jpeg"}],"author":"elena","twitter_card":"summary_large_image","twitter_misc":{"Written by":"elena","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/#article","isPartOf":{"@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/"},"author":{"name":"elena","@id":"https:\/\/giflex.it\/#\/schema\/person\/41056efa2ab4cc1ae4953882b8ec42d6"},"headline":"Performance ambientali sotto controllo con il tool FpS","datePublished":"2022-03-10T08:50:21+00:00","mainEntityOfPage":{"@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/"},"wordCount":100,"commentCount":0,"image":{"@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","articleSection":["Sostenibilit\u00e0"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/","url":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/","name":"Performance ambientali sotto controllo con il tool FpS - Giflex","isPartOf":{"@id":"https:\/\/giflex.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/#primaryimage"},"image":{"@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","datePublished":"2022-03-10T08:50:21+00:00","author":{"@id":"https:\/\/giflex.it\/#\/schema\/person\/41056efa2ab4cc1ae4953882b8ec42d6"},"breadcrumb":{"@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/#primaryimage","url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","contentUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","width":2560,"height":1486},{"@type":"BreadcrumbList","@id":"https:\/\/giflex.it\/2022\/03\/10\/performance-ambientali-sotto-controllo-con-il-tool-fps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giflex.it\/"},{"@type":"ListItem","position":2,"name":"Performance ambientali sotto controllo con il tool FpS"}]},{"@type":"WebSite","@id":"https:\/\/giflex.it\/#website","url":"https:\/\/giflex.it\/","name":"Giflex","description":"Italian Flexible Packaging Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giflex.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/giflex.it\/#\/schema\/person\/41056efa2ab4cc1ae4953882b8ec42d6","name":"elena","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g","caption":"elena"},"url":"https:\/\/giflex.it\/en\/author\/elena\/"}]}},"_links":{"self":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/3064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/comments?post=3064"}],"version-history":[{"count":1,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/3064\/revisions"}],"predecessor-version":[{"id":3065,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/3064\/revisions\/3065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media\/2999"}],"wp:attachment":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media?parent=3064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/categories?post=3064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/tags?post=3064"},{"taxonomy":"fonte","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/fonte?post=3064"},{"taxonomy":"posizione","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posizione?post=3064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}