{"id":2998,"date":"2022-02-14T10:21:22","date_gmt":"2022-02-14T09:21:22","guid":{"rendered":"https:\/\/federazionecartagrafica.it\/?p=3132"},"modified":"2022-03-01T12:10:22","modified_gmt":"2022-03-01T11:10:22","slug":"progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo","status":"publish","type":"post","link":"https:\/\/giflex.it\/en\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/","title":{"rendered":"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo"},"content":{"rendered":"<p>Accompagnare le imprese a <strong>rispettare gli obblighi e indicazioni sulla crescita sostenibile<\/strong> previste delle nuove regole di Tassonomia dell&#8217;Unione Europea, ma soprattutto fornire gli strumenti per fare della sostenibilit\u00e0 una vera leva di crescita. Sono gli obiettivi del<strong> Progetto Sostenibilit\u00e0 della Federazione Carta e Grafica<\/strong> che sar\u00e0 presentato il prossimo <strong>1 marzo, alle ore 15<\/strong>, attraverso l&#8217;incontro <strong>webinar<\/strong> &#8220;<strong>Federazione per la Sostenibilit\u00e0: una metodologia e un software per tutte le aziende<\/strong>&#8220;.<\/p>\n<p>Il \u201cProgetto Sostenibilit\u00e0\u201d della Federazione, come da titolo dell&#8217;incontro, <strong>fissa una metodologia<\/strong> &#8211; fondata sugli standard internazionali di rendicontazione e coerente con tutti gli obiettivi europei richiamati dalla Tassonomia &#8211; e <strong>rende disponibile un software<\/strong> attraverso il quale le imprese potranno eseguire la <strong>preventiva autovalutazione degli impatti e del relativo grado di sostenibilit\u00e0<\/strong>, quindi <strong>accedere al livello di rendicontazione pi\u00f9 appropriato<\/strong> in base alla tipologia dell&#8217;attivit\u00e0 e delle dimensioni aziendali.<\/p>\n<p>Le nuove Direttive, in base alle proposte della Commissione UE, dovrebbero entrare in vigore dal prossimo anno. Le scelte metodologiche del Progetto Sostenibilit\u00e0 della Federazione Carta e Grafica <strong>anticipano la previsione dell\u2019estensione della rendicontazione alle PMI<\/strong>: al di l\u00e0 dell\u2019obbligatoriet\u00e0, le aziende della filiera sono chiamate alla <strong>sfida della sostenibilit\u00e0 e della transizione ecologica in quanto parti integranti di supply chain complesse<\/strong>, che costituiscono un settore vitale per il sistema Italia. Il Progetto Sostenibilit\u00e0 \u00e8 stato avviato agli inizi del 2020, coinvolgendo le aziende delle Associazioni costituenti la Federazione, <strong>Acimga<\/strong>, <strong>Assocarta<\/strong> e <strong>Assografici<\/strong>, con il sostegno del socio aggregato <strong>Comieco<\/strong> e di <strong>Unisalute,<\/strong>\u00a0con la consulenza di <strong>BDO<\/strong> ed in confronto continuo con il <strong>Forum per la Finanza Sostenibile<\/strong>.<\/p>\n<p><a href=\"https:\/\/federazionecartagrafica.it\/wp-content\/uploads\/sites\/2\/2022\/02\/Prot-DG-2022-06-All1_Locandina_MARZO-2022_FCG_WEBINAR.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-3131 size-medium\" src=\"https:\/\/federazionecartagrafica.it\/wp-content\/uploads\/sites\/2\/2022\/02\/Schermata-2022-02-14-alle-10.00.26-220x300.png\" alt=\"\" width=\"220\" height=\"300\" \/><\/a>L&#8217;incontro del 1 marzo (<a href=\"https:\/\/federazionecartagrafica.it\/wp-content\/uploads\/sites\/2\/2022\/02\/Prot-DG-2022-06-All1_Locandina_MARZO-2022_FCG_WEBINAR.pdf\" target=\"_blank\" rel=\"noopener\">qui la locandina contenente il link per l&#8217;iscrizione<\/a>) sar\u00e0 introdotto da <strong>Carlo Emanuele Bona<\/strong>, Presidente della Federazione Carta e Grafica e da <strong>Cristina Piovesana<\/strong>, Vice Presidente per l&#8217;Ambiente, la Sostenibilit\u00e0 e la Cultura di Confindustria. La presentazione del &#8220;FpS Tool&#8221;, lo strumento software per la Sostenibilit\u00e0 sviluppato ad hoc, sar\u00e0 curata dai referenti del Progetto <strong>Elisabetta Bottazzoli<\/strong>, <strong>Italo Vailati<\/strong> e <strong>Massimo Ramunni<\/strong>. Sono previsti interventi di <strong>Massimo Baldelli<\/strong> di Unisalute e di <strong>Lorenzo Bono<\/strong>, responsabile dell&#8217;area ricerca e sviluppo di Comieco. Le conclusioni dell&#8217;incontro, moderato dal Direttore della Federazione Carta e Grafica<strong> Massimo Medugno<\/strong>, sono affidate al Direttore di Acimga <strong>Andrea Briganti<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Accompagnare le imprese a rispettare gli obblighi e indicazioni sulla crescita sostenibile previste delle nuove regole di Tassonomia dell&#8217;Unione Europea, ma soprattutto fornire gli strumenti per fare della sostenibilit\u00e0 una vera leva di crescita. Sono gli obiettivi del Progetto Sostenibilit\u00e0 della Federazione Carta e Grafica che sar\u00e0 presentato il prossimo 1 marzo, alle ore 15, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":2999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[75,15],"tags":[],"fonte":[],"posizione":[7],"class_list":["post-2998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita","category-transizione-green","posizione-news-giflex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo - Giflex<\/title>\n<meta name=\"description\" content=\"Il Progetto fissa una metodologia e rende disponibile un software attraverso il quale le imprese potranno eseguire la preventiva autovalutazione degli impatti e del relativo grado di sostenibilit\u00e0, quindi accedere al livello di rendicontazione pi\u00f9 appropriato in base alla tipologia dell&#039;attivit\u00e0 e delle dimensioni aziendali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo - Giflex\" \/>\n<meta property=\"og:description\" content=\"Il Progetto fissa una metodologia e rende disponibile un software attraverso il quale le imprese potranno eseguire la preventiva autovalutazione degli impatti e del relativo grado di sostenibilit\u00e0, quindi accedere al livello di rendicontazione pi\u00f9 appropriato in base alla tipologia dell&#039;attivit\u00e0 e delle dimensioni aziendali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/\" \/>\n<meta property=\"og:site_name\" content=\"Giflex\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-14T09:21:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-01T11:10:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"enricosbandi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"enricosbandi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/\"},\"author\":{\"name\":\"enricosbandi\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/0a527942a7bba1368f20325090c35556\"},\"headline\":\"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo\",\"datePublished\":\"2022-02-14T09:21:22+00:00\",\"dateModified\":\"2022-03-01T11:10:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/\"},\"wordCount\":381,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/02\\\/locandina_sostenibilita-scaled.jpg\",\"articleSection\":[\"Sostenibilit\u00e0\",\"transizione-green\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/\",\"url\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/\",\"name\":\"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo - Giflex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/02\\\/locandina_sostenibilita-scaled.jpg\",\"datePublished\":\"2022-02-14T09:21:22+00:00\",\"dateModified\":\"2022-03-01T11:10:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/0a527942a7bba1368f20325090c35556\"},\"description\":\"Il Progetto fissa una metodologia e rende disponibile un software attraverso il quale le imprese potranno eseguire la preventiva autovalutazione degli impatti e del relativo grado di sostenibilit\u00e0, quindi accedere al livello di rendicontazione pi\u00f9 appropriato in base alla tipologia dell'attivit\u00e0 e delle dimensioni aziendali.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/02\\\/locandina_sostenibilita-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/02\\\/locandina_sostenibilita-scaled.jpg\",\"width\":2560,\"height\":1486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2022\\\/02\\\/14\\\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giflex.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\",\"url\":\"https:\\\/\\\/giflex.it\\\/\",\"name\":\"Giflex\",\"description\":\"Italian Flexible Packaging Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giflex.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/0a527942a7bba1368f20325090c35556\",\"name\":\"enricosbandi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fab3e07d7a1fefcc017d11e895c925f926d3a539b828129bb54949a8ac834d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fab3e07d7a1fefcc017d11e895c925f926d3a539b828129bb54949a8ac834d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fab3e07d7a1fefcc017d11e895c925f926d3a539b828129bb54949a8ac834d5?s=96&d=mm&r=g\",\"caption\":\"enricosbandi\"},\"url\":\"https:\\\/\\\/giflex.it\\\/en\\\/author\\\/enricosbandi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo - Giflex","description":"Il Progetto fissa una metodologia e rende disponibile un software attraverso il quale le imprese potranno eseguire la preventiva autovalutazione degli impatti e del relativo grado di sostenibilit\u00e0, quindi accedere al livello di rendicontazione pi\u00f9 appropriato in base alla tipologia dell'attivit\u00e0 e delle dimensioni aziendali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/","og_locale":"en_US","og_type":"article","og_title":"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo - Giflex","og_description":"Il Progetto fissa una metodologia e rende disponibile un software attraverso il quale le imprese potranno eseguire la preventiva autovalutazione degli impatti e del relativo grado di sostenibilit\u00e0, quindi accedere al livello di rendicontazione pi\u00f9 appropriato in base alla tipologia dell'attivit\u00e0 e delle dimensioni aziendali.","og_url":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/","og_site_name":"Giflex","article_published_time":"2022-02-14T09:21:22+00:00","article_modified_time":"2022-03-01T11:10:22+00:00","og_image":[{"width":2560,"height":1486,"url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","type":"image\/jpeg"}],"author":"enricosbandi","twitter_card":"summary_large_image","twitter_misc":{"Written by":"enricosbandi","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/#article","isPartOf":{"@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/"},"author":{"name":"enricosbandi","@id":"https:\/\/giflex.it\/#\/schema\/person\/0a527942a7bba1368f20325090c35556"},"headline":"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo","datePublished":"2022-02-14T09:21:22+00:00","dateModified":"2022-03-01T11:10:22+00:00","mainEntityOfPage":{"@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/"},"wordCount":381,"commentCount":0,"image":{"@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","articleSection":["Sostenibilit\u00e0","transizione-green"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/","url":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/","name":"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo - Giflex","isPartOf":{"@id":"https:\/\/giflex.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/#primaryimage"},"image":{"@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","datePublished":"2022-02-14T09:21:22+00:00","dateModified":"2022-03-01T11:10:22+00:00","author":{"@id":"https:\/\/giflex.it\/#\/schema\/person\/0a527942a7bba1368f20325090c35556"},"description":"Il Progetto fissa una metodologia e rende disponibile un software attraverso il quale le imprese potranno eseguire la preventiva autovalutazione degli impatti e del relativo grado di sostenibilit\u00e0, quindi accedere al livello di rendicontazione pi\u00f9 appropriato in base alla tipologia dell'attivit\u00e0 e delle dimensioni aziendali.","breadcrumb":{"@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/#primaryimage","url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","contentUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2022\/02\/locandina_sostenibilita-scaled.jpg","width":2560,"height":1486},{"@type":"BreadcrumbList","@id":"https:\/\/giflex.it\/2022\/02\/14\/progetto-sostenibilita-della-federazione-presentazione-in-webinar-il-1-marzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giflex.it\/"},{"@type":"ListItem","position":2,"name":"Progetto Sostenibilit\u00e0 della Federazione: presentazione in webinar il 1\u00b0 marzo"}]},{"@type":"WebSite","@id":"https:\/\/giflex.it\/#website","url":"https:\/\/giflex.it\/","name":"Giflex","description":"Italian Flexible Packaging Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giflex.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/giflex.it\/#\/schema\/person\/0a527942a7bba1368f20325090c35556","name":"enricosbandi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5fab3e07d7a1fefcc017d11e895c925f926d3a539b828129bb54949a8ac834d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fab3e07d7a1fefcc017d11e895c925f926d3a539b828129bb54949a8ac834d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fab3e07d7a1fefcc017d11e895c925f926d3a539b828129bb54949a8ac834d5?s=96&d=mm&r=g","caption":"enricosbandi"},"url":"https:\/\/giflex.it\/en\/author\/enricosbandi\/"}]}},"_links":{"self":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/2998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/comments?post=2998"}],"version-history":[{"count":1,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/2998\/revisions"}],"predecessor-version":[{"id":3004,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/2998\/revisions\/3004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media\/2999"}],"wp:attachment":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media?parent=2998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/categories?post=2998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/tags?post=2998"},{"taxonomy":"fonte","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/fonte?post=2998"},{"taxonomy":"posizione","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posizione?post=2998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}