{"id":2589,"date":"2021-12-15T12:14:06","date_gmt":"2021-12-15T11:14:06","guid":{"rendered":"https:\/\/giflex.it\/?p=2589"},"modified":"2021-12-20T12:19:35","modified_gmt":"2021-12-20T11:19:35","slug":"il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata","status":"publish","type":"post","link":"https:\/\/giflex.it\/en\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/","title":{"rendered":"Il mondo del packaging chiede chiarezza all&#8217;UE per orientare il consumatore nella differenziata"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1169 alignleft\" src=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2021\/11\/08-Italo-Vailati2.jpg\" alt=\"\" width=\"213\" height=\"213\" \/>&#8220;Il problema del fine vita degli imballaggi \u00e8 un tema quanto mai attuale e discusso a tutti i livelli, sia in Italia che in tutta Europa.<\/p>\n<p>Le pi\u00f9 recenti disposizioni legislative spingono per arrivare ad utilizzare in tempi relativamente brevi solo imballaggi riciclabili, puntando molto sulla raccolta differenziata urbana come principale canale per il conferimento degli imballaggi alla fine del loro ciclo di vita.<\/p>\n<p>Per arrivare ad ottenere i target di raccolta e riciclo previsti per il 2030 diventa essenziale il ruolo dei consumatori che devono essere sempre pi\u00f9 orientati a esercitare la raccolta differenziata degli imballi.<\/p>\n<p>Per far ci\u00f2 \u00e8 importante che tutte le nazioni adottino sistemi comuni e condivisi di raccolta differenziata, soprattutto si stabiliscano regole uniche e precise di marcatura degli imballaggi per facilitare le operazioni di smaltimento da parte dei consumatori.<\/p>\n<p>Il documento allegato, firmato da tutte le principali associazioni europee che rappresentano i produttori e utilizzatori di packaging, riassume il punto di vista del mondo industriale e riporta richieste precise inviate alle autorit\u00e0 europee perch\u00e9 si adoperino per stabilire regole comuni e condivise al fine d\u2019implementare la raccolta differenziata e il riciclo degli imballaggi&#8221;.<\/p>\n<p>Italo Vailati &#8211; Segretario Giflex<\/p>\n<p>Di seguito il documento per consultazione:<\/p>\n<p><a href=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2021\/12\/Joint-position-EU-harmonised-consumer-sorting-instructions_FINAL.pdf\" target=\"_blank\" rel=\"noopener\">Joint position EU harmonised consumer sorting instructions<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Il problema del fine vita degli imballaggi \u00e8 un tema quanto mai attuale e discusso a tutti i livelli, sia in Italia che in tutta Europa.<\/p>\n<p>Le pi\u00f9 recenti disposizioni legislative spingono per arrivare ad utilizzare in tempi relativamente brevi solo imballaggi riciclabili [&#8230;]&#8221;<\/p>\n","protected":false},"author":9,"featured_media":1169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[75],"tags":[],"fonte":[],"posizione":[7],"class_list":["post-2589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita","posizione-news-giflex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il mondo del packaging chiede chiarezza all&#039;UE per orientare il consumatore nella differenziata - Giflex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il mondo del packaging chiede chiarezza all&#039;UE per orientare il consumatore nella differenziata - Giflex\" \/>\n<meta property=\"og:description\" content=\"&quot;Il problema del fine vita degli imballaggi \u00e8 un tema quanto mai attuale e discusso a tutti i livelli, sia in Italia che in tutta Europa.  Le pi\u00f9 recenti disposizioni legislative spingono per arrivare ad utilizzare in tempi relativamente brevi solo imballaggi riciclabili [...]&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/\" \/>\n<meta property=\"og:site_name\" content=\"Giflex\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T11:14:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-20T11:19:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2021\/11\/08-Italo-Vailati2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elena\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"elena\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/\"},\"author\":{\"name\":\"elena\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/41056efa2ab4cc1ae4953882b8ec42d6\"},\"headline\":\"Il mondo del packaging chiede chiarezza all&#8217;UE per orientare il consumatore nella differenziata\",\"datePublished\":\"2021-12-15T11:14:06+00:00\",\"dateModified\":\"2021-12-20T11:19:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/\"},\"wordCount\":219,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/11\\\/08-Italo-Vailati2.jpg\",\"articleSection\":[\"Sostenibilit\u00e0\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/\",\"url\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/\",\"name\":\"Il mondo del packaging chiede chiarezza all'UE per orientare il consumatore nella differenziata - Giflex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/11\\\/08-Italo-Vailati2.jpg\",\"datePublished\":\"2021-12-15T11:14:06+00:00\",\"dateModified\":\"2021-12-20T11:19:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/41056efa2ab4cc1ae4953882b8ec42d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/11\\\/08-Italo-Vailati2.jpg\",\"contentUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/11\\\/08-Italo-Vailati2.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2021\\\/12\\\/15\\\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giflex.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il mondo del packaging chiede chiarezza all&#8217;UE per orientare il consumatore nella differenziata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\",\"url\":\"https:\\\/\\\/giflex.it\\\/\",\"name\":\"Giflex\",\"description\":\"Italian Flexible Packaging Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giflex.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/41056efa2ab4cc1ae4953882b8ec42d6\",\"name\":\"elena\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g\",\"caption\":\"elena\"},\"url\":\"https:\\\/\\\/giflex.it\\\/en\\\/author\\\/elena\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il mondo del packaging chiede chiarezza all'UE per orientare il consumatore nella differenziata - Giflex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/","og_locale":"en_US","og_type":"article","og_title":"Il mondo del packaging chiede chiarezza all'UE per orientare il consumatore nella differenziata - Giflex","og_description":"\"Il problema del fine vita degli imballaggi \u00e8 un tema quanto mai attuale e discusso a tutti i livelli, sia in Italia che in tutta Europa.  Le pi\u00f9 recenti disposizioni legislative spingono per arrivare ad utilizzare in tempi relativamente brevi solo imballaggi riciclabili [...]\"","og_url":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/","og_site_name":"Giflex","article_published_time":"2021-12-15T11:14:06+00:00","article_modified_time":"2021-12-20T11:19:35+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2021\/11\/08-Italo-Vailati2.jpg","type":"image\/jpeg"}],"author":"elena","twitter_card":"summary_large_image","twitter_misc":{"Written by":"elena","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/#article","isPartOf":{"@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/"},"author":{"name":"elena","@id":"https:\/\/giflex.it\/#\/schema\/person\/41056efa2ab4cc1ae4953882b8ec42d6"},"headline":"Il mondo del packaging chiede chiarezza all&#8217;UE per orientare il consumatore nella differenziata","datePublished":"2021-12-15T11:14:06+00:00","dateModified":"2021-12-20T11:19:35+00:00","mainEntityOfPage":{"@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/"},"wordCount":219,"commentCount":0,"image":{"@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2021\/11\/08-Italo-Vailati2.jpg","articleSection":["Sostenibilit\u00e0"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/","url":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/","name":"Il mondo del packaging chiede chiarezza all'UE per orientare il consumatore nella differenziata - Giflex","isPartOf":{"@id":"https:\/\/giflex.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/#primaryimage"},"image":{"@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2021\/11\/08-Italo-Vailati2.jpg","datePublished":"2021-12-15T11:14:06+00:00","dateModified":"2021-12-20T11:19:35+00:00","author":{"@id":"https:\/\/giflex.it\/#\/schema\/person\/41056efa2ab4cc1ae4953882b8ec42d6"},"breadcrumb":{"@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/#primaryimage","url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2021\/11\/08-Italo-Vailati2.jpg","contentUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2021\/11\/08-Italo-Vailati2.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/giflex.it\/2021\/12\/15\/il-mondo-del-packaging-chiede-chiarezza-allue-per-orientare-il-consumatore-nella-differenziata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giflex.it\/"},{"@type":"ListItem","position":2,"name":"Il mondo del packaging chiede chiarezza all&#8217;UE per orientare il consumatore nella differenziata"}]},{"@type":"WebSite","@id":"https:\/\/giflex.it\/#website","url":"https:\/\/giflex.it\/","name":"Giflex","description":"Italian Flexible Packaging Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giflex.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/giflex.it\/#\/schema\/person\/41056efa2ab4cc1ae4953882b8ec42d6","name":"elena","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d525111e4e1ae5a4d80e26ec00a9d4a6b805b9bc83c81680c793b7ffc261ca2b?s=96&d=mm&r=g","caption":"elena"},"url":"https:\/\/giflex.it\/en\/author\/elena\/"}]}},"_links":{"self":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/2589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/comments?post=2589"}],"version-history":[{"count":5,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/2589\/revisions"}],"predecessor-version":[{"id":2595,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/2589\/revisions\/2595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media\/1169"}],"wp:attachment":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media?parent=2589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/categories?post=2589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/tags?post=2589"},{"taxonomy":"fonte","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/fonte?post=2589"},{"taxonomy":"posizione","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posizione?post=2589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}