{"id":12198,"date":"2026-07-23T18:29:06","date_gmt":"2026-07-23T16:29:06","guid":{"rendered":"https:\/\/giflex.it\/?p=12198"},"modified":"2026-07-24T10:06:52","modified_gmt":"2026-07-24T08:06:52","slug":"giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea","status":"publish","type":"post","link":"https:\/\/giflex.it\/en\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/","title":{"rendered":"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea"},"content":{"rendered":"<div id=\"attachment_12153\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/giflex.it\/chi-siamo\/#governance\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-12153\" class=\"wp-image-12153 size-medium\" src=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/06\/fotoweb-162-3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><p id=\"caption-attachment-12153\" class=\"wp-caption-text\">Clicca l&#8217;immagine per scoprire la pagina dedicata alla Governance Giflex.<\/p><\/div>\n<p>A poco pi\u00f9 di un mese dalla sua elezione alla Presidenza di Giflex, Neni Rossini ha annunciato la composizione della squadra che l\u2019affiancher\u00e0 nel suo mandato. Una governance nel segno della continuit\u00e0, della filiera e della visione europea.<\/p>\n<p>In una fase cruciale per il settore, chiamato a confrontarsi con l&#8217;attuazione del nuovo quadro normativo europeo sugli imballaggi e con le sfide della transizione sostenibile, la rieletta governance associativa consolida l&#8217;obiettivo di rafforzare il ruolo di Giflex quale interlocutore autorevole delle istituzioni, in Italia e a Bruxelles, promuovendo la competitivit\u00e0 delle imprese associate e il valore del packaging flessibile all&#8217;interno dell&#8217;economia circolare.<\/p>\n<p>Il nuovo <strong>Comitato esecutivo<\/strong> \u00e8 cos\u00ec composto:<\/p>\n<p><strong>Vicepresidenti:<\/strong><\/p>\n<ul>\n<li><strong>Andrea D&#8217;Amato<\/strong> (Seda Italy) Presidente di Federazione Carta e Grafica, la cui presenza rafforza il raccordo con l&#8217;intera filiera del packaging;<\/li>\n<li><strong>Michele Guala<\/strong> (Gualapack) Vicepresidente di Flexible Packaging Europe (FPE), l\u2019associazione europea che garantisce un presidio diretto a Bruxelles delle politiche europee del settore.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Past President<\/strong>:<\/p>\n<ul>\n<li><strong>Alberto Palaveri<\/strong> (Sacchital Group) Vicepresidente di Assografici, per Giflex con delega al rafforzamento del dialogo istituzionale a livello nazionale e di rappresentanza politica, in continuit\u00e0 con il lavoro svolto durante il suo mandato da Presidente.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Tesoriere:<\/strong><\/p>\n<ul>\n<li><strong>Elena Peron<\/strong> (Amcor Flexibles Italia).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Membri Comitato Esecutivo:<\/strong><\/p>\n<ul>\n<li><strong>Elisabetta Boriani<\/strong> (Lavorazione Carte Speciali);<\/li>\n<li><strong>Ruggero Gerosa<\/strong> (Gerosa Group);<\/li>\n<li><strong>Marco Mensitieri<\/strong> (Icimendue);<\/li>\n<li><strong>Luca Santandrea<\/strong> (Masterpack);<\/li>\n<li><strong>Lara Selvi<\/strong> (Saica Flex Italia);<\/li>\n<li><strong>Stefano Trombetta<\/strong> (Goglio);<\/li>\n<li><strong>Giselda Virno<\/strong> (Di Mauro Officine Grafiche).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&#8220;La nuova governance nasce con l&#8217;obiettivo di valorizzare le competenze presenti all&#8217;interno dell&#8217;Associazione e di affrontare con spirito di squadra le sfide che attendono il nostro settore&#8221;, dichiara la Presidente Neni Rossini. &#8220;In uno scenario caratterizzato da importanti evoluzioni normative, a partire dal quadro europeo sul packaging, Giflex continuer\u00e0 a essere un interlocutore autorevole per le istituzioni e un punto di riferimento per le imprese associate, promuovendo il valore dell&#8217;imballaggio flessibile come leva di innovazione, sostenibilit\u00e0 e competitivit\u00e0.&#8221;<\/p>\n<p>Con questa rappresentanza Giflex conferma la volont\u00e0 di promuovere il dialogo lungo l&#8217;intera filiera e sostenere lo sviluppo del settore attraverso un confronto costante con gli stakeholder nazionali ed europei.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A poco pi\u00f9 di un mese dalla sua elezione alla Presidenza di Giflex, Neni Rossini ha annunciato la composizione della squadra che l\u2019affiancher\u00e0 nel suo mandato. Una governance nel segno della continuit\u00e0, della filiera e della visione europea. In una fase cruciale per il settore, chiamato a confrontarsi con l&#8217;attuazione del nuovo quadro normativo europeo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[63],"tags":[],"fonte":[174],"posizione":[7],"class_list":["post-12198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vita-associativa","fonte-giflex","posizione-news-giflex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea - Giflex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea - Giflex\" \/>\n<meta property=\"og:description\" content=\"A poco pi\u00f9 di un mese dalla sua elezione alla Presidenza di Giflex, Neni Rossini ha annunciato la composizione della squadra che l\u2019affiancher\u00e0 nel suo mandato. Una governance nel segno della continuit\u00e0, della filiera e della visione europea. In una fase cruciale per il settore, chiamato a confrontarsi con l&#8217;attuazione del nuovo quadro normativo europeo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/\" \/>\n<meta property=\"og:site_name\" content=\"Giflex\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-23T16:29:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-24T08:06:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/06\/fotoweb-162-3-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paolo Giovenzana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paolo Giovenzana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/\"},\"author\":{\"name\":\"Paolo Giovenzana\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/9fda58bd92203f69ec32c836be0bd030\"},\"headline\":\"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea\",\"datePublished\":\"2026-07-23T16:29:06+00:00\",\"dateModified\":\"2026-07-24T08:06:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/\"},\"wordCount\":383,\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/fotoweb-162-3-scaled.jpg\",\"articleSection\":[\"Vita associativa\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/\",\"url\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/\",\"name\":\"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea - Giflex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/fotoweb-162-3-scaled.jpg\",\"datePublished\":\"2026-07-23T16:29:06+00:00\",\"dateModified\":\"2026-07-24T08:06:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/9fda58bd92203f69ec32c836be0bd030\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/fotoweb-162-3-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/fotoweb-162-3-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giflex.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\",\"url\":\"https:\\\/\\\/giflex.it\\\/\",\"name\":\"Giflex\",\"description\":\"Italian Flexible Packaging Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giflex.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/9fda58bd92203f69ec32c836be0bd030\",\"name\":\"Paolo Giovenzana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g\",\"caption\":\"Paolo Giovenzana\"},\"description\":\"prova\",\"sameAs\":[\"https:\\\/\\\/federazionecartagrafica.it\"],\"url\":\"https:\\\/\\\/giflex.it\\\/en\\\/author\\\/paologiove\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea - Giflex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/","og_locale":"en_US","og_type":"article","og_title":"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea - Giflex","og_description":"A poco pi\u00f9 di un mese dalla sua elezione alla Presidenza di Giflex, Neni Rossini ha annunciato la composizione della squadra che l\u2019affiancher\u00e0 nel suo mandato. Una governance nel segno della continuit\u00e0, della filiera e della visione europea. In una fase cruciale per il settore, chiamato a confrontarsi con l&#8217;attuazione del nuovo quadro normativo europeo [&hellip;]","og_url":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/","og_site_name":"Giflex","article_published_time":"2026-07-23T16:29:06+00:00","article_modified_time":"2026-07-24T08:06:52+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/06\/fotoweb-162-3-scaled.jpg","type":"image\/jpeg"}],"author":"Paolo Giovenzana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Paolo Giovenzana","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/#article","isPartOf":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/"},"author":{"name":"Paolo Giovenzana","@id":"https:\/\/giflex.it\/#\/schema\/person\/9fda58bd92203f69ec32c836be0bd030"},"headline":"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea","datePublished":"2026-07-23T16:29:06+00:00","dateModified":"2026-07-24T08:06:52+00:00","mainEntityOfPage":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/"},"wordCount":383,"image":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/06\/fotoweb-162-3-scaled.jpg","articleSection":["Vita associativa"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/","url":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/","name":"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea - Giflex","isPartOf":{"@id":"https:\/\/giflex.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/#primaryimage"},"image":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/06\/fotoweb-162-3-scaled.jpg","datePublished":"2026-07-23T16:29:06+00:00","dateModified":"2026-07-24T08:06:52+00:00","author":{"@id":"https:\/\/giflex.it\/#\/schema\/person\/9fda58bd92203f69ec32c836be0bd030"},"breadcrumb":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/#primaryimage","url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/06\/fotoweb-162-3-scaled.jpg","contentUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/06\/fotoweb-162-3-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-nuova-governance-nel-segno-della-continuita-della-filiera-e-della-visione-europea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giflex.it\/"},{"@type":"ListItem","position":2,"name":"Giflex, nuova governance nel segno della continuit\u00e0, della filiera e della visione europea"}]},{"@type":"WebSite","@id":"https:\/\/giflex.it\/#website","url":"https:\/\/giflex.it\/","name":"Giflex","description":"Italian Flexible Packaging Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giflex.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/giflex.it\/#\/schema\/person\/9fda58bd92203f69ec32c836be0bd030","name":"Paolo Giovenzana","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g","caption":"Paolo Giovenzana"},"description":"prova","sameAs":["https:\/\/federazionecartagrafica.it"],"url":"https:\/\/giflex.it\/en\/author\/paologiove\/"}]}},"_links":{"self":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/12198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/comments?post=12198"}],"version-history":[{"count":4,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/12198\/revisions"}],"predecessor-version":[{"id":12221,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/12198\/revisions\/12221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media\/12153"}],"wp:attachment":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media?parent=12198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/categories?post=12198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/tags?post=12198"},{"taxonomy":"fonte","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/fonte?post=12198"},{"taxonomy":"posizione","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posizione?post=12198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}