{"id":12194,"date":"2026-07-23T18:25:08","date_gmt":"2026-07-23T16:25:08","guid":{"rendered":"https:\/\/giflex.it\/?p=12194"},"modified":"2026-07-24T14:31:25","modified_gmt":"2026-07-24T12:31:25","slug":"giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni","status":"publish","type":"post","link":"https:\/\/giflex.it\/en\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/","title":{"rendered":"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12196 alignleft\" src=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/07\/Micol-Bertoni-jpg.jpg\" alt=\"\" width=\"330\" height=\"413\" \/>Siamo lieti di dare il benvenuto nel team <strong>Giflex<\/strong> a <strong>Micol<\/strong><strong> Bertoni<\/strong>.<br \/>\nBertoni ricoprir\u00e0 il ruolo di <strong>Responsabile Relazioni Istituzionali Italia e Europa<\/strong> di <strong>Assografici<\/strong> e di <strong>Giflex<\/strong>: l\u2019incarico si estende quindi con particolare attenzione e presidio all&#8217;attivit\u00e0 e ai temi cari al gruppo.<\/p>\n<p>Uno degli obiettivi sar\u00e0 rafforzare il posizionamento dell&#8217;associazione nel dialogo con le istituzioni nazionali ed europee, sviluppare strategie di advocacy e stakeholder engagement, e incidere sempre di pi\u00f9 sul quadro normativo che riguarda il settore dell&#8217;imballaggio flessibile.<\/p>\n<p>Quello di Micol Bertoni \u00e8 un profilo di grande esperienza nell\u2019ambito delle relazioni istituzionali, che arricchisce ulteriormente la nostra squadra in un momento in cui far sentire la voce del settore \u00e8 pi\u00f9 importante che mai.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo lieti di dare il benvenuto nel team Giflex a Micol Bertoni. Bertoni ricoprir\u00e0 il ruolo di Responsabile Relazioni Istituzionali Italia e Europa di Assografici e di Giflex: l\u2019incarico si estende quindi con particolare attenzione e presidio all&#8217;attivit\u00e0 e ai temi cari al gruppo. Uno degli obiettivi sar\u00e0 rafforzare il posizionamento dell&#8217;associazione nel dialogo con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[189],"tags":[],"fonte":[174],"posizione":[7],"class_list":["post-12194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nomine","fonte-giflex","posizione-news-giflex"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni - Giflex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni - Giflex\" \/>\n<meta property=\"og:description\" content=\"Siamo lieti di dare il benvenuto nel team Giflex a Micol Bertoni. Bertoni ricoprir\u00e0 il ruolo di Responsabile Relazioni Istituzionali Italia e Europa di Assografici e di Giflex: l\u2019incarico si estende quindi con particolare attenzione e presidio all&#8217;attivit\u00e0 e ai temi cari al gruppo. Uno degli obiettivi sar\u00e0 rafforzare il posizionamento dell&#8217;associazione nel dialogo con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/\" \/>\n<meta property=\"og:site_name\" content=\"Giflex\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-23T16:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-24T12:31:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/07\/micol-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paolo Giovenzana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paolo Giovenzana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/\"},\"author\":{\"name\":\"Paolo Giovenzana\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/9fda58bd92203f69ec32c836be0bd030\"},\"headline\":\"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni\",\"datePublished\":\"2026-07-23T16:25:08+00:00\",\"dateModified\":\"2026-07-24T12:31:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/\"},\"wordCount\":130,\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/micol-1.jpg\",\"articleSection\":[\"nomine\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/\",\"url\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/\",\"name\":\"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni - Giflex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/micol-1.jpg\",\"datePublished\":\"2026-07-23T16:25:08+00:00\",\"dateModified\":\"2026-07-24T12:31:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/9fda58bd92203f69ec32c836be0bd030\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/micol-1.jpg\",\"contentUrl\":\"https:\\\/\\\/giflex.it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/micol-1.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giflex.it\\\/2026\\\/07\\\/23\\\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giflex.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#website\",\"url\":\"https:\\\/\\\/giflex.it\\\/\",\"name\":\"Giflex\",\"description\":\"Italian Flexible Packaging Association\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/giflex.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/giflex.it\\\/#\\\/schema\\\/person\\\/9fda58bd92203f69ec32c836be0bd030\",\"name\":\"Paolo Giovenzana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g\",\"caption\":\"Paolo Giovenzana\"},\"description\":\"prova\",\"sameAs\":[\"https:\\\/\\\/federazionecartagrafica.it\"],\"url\":\"https:\\\/\\\/giflex.it\\\/en\\\/author\\\/paologiove\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni - Giflex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/","og_locale":"en_US","og_type":"article","og_title":"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni - Giflex","og_description":"Siamo lieti di dare il benvenuto nel team Giflex a Micol Bertoni. Bertoni ricoprir\u00e0 il ruolo di Responsabile Relazioni Istituzionali Italia e Europa di Assografici e di Giflex: l\u2019incarico si estende quindi con particolare attenzione e presidio all&#8217;attivit\u00e0 e ai temi cari al gruppo. Uno degli obiettivi sar\u00e0 rafforzare il posizionamento dell&#8217;associazione nel dialogo con [&hellip;]","og_url":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/","og_site_name":"Giflex","article_published_time":"2026-07-23T16:25:08+00:00","article_modified_time":"2026-07-24T12:31:25+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/07\/micol-1.jpg","type":"image\/jpeg"}],"author":"Paolo Giovenzana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Paolo Giovenzana","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/#article","isPartOf":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/"},"author":{"name":"Paolo Giovenzana","@id":"https:\/\/giflex.it\/#\/schema\/person\/9fda58bd92203f69ec32c836be0bd030"},"headline":"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni","datePublished":"2026-07-23T16:25:08+00:00","dateModified":"2026-07-24T12:31:25+00:00","mainEntityOfPage":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/"},"wordCount":130,"image":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/07\/micol-1.jpg","articleSection":["nomine"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/","url":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/","name":"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni - Giflex","isPartOf":{"@id":"https:\/\/giflex.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/#primaryimage"},"image":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/#primaryimage"},"thumbnailUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/07\/micol-1.jpg","datePublished":"2026-07-23T16:25:08+00:00","dateModified":"2026-07-24T12:31:25+00:00","author":{"@id":"https:\/\/giflex.it\/#\/schema\/person\/9fda58bd92203f69ec32c836be0bd030"},"breadcrumb":{"@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/#primaryimage","url":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/07\/micol-1.jpg","contentUrl":"https:\/\/giflex.it\/wp-content\/uploads\/sites\/5\/2026\/07\/micol-1.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/giflex.it\/2026\/07\/23\/giflex-rafforza-la-squadra-con-lingresso-di-micol-bertoni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/giflex.it\/"},{"@type":"ListItem","position":2,"name":"Giflex rafforza la squadra con l\u2019ingresso di Micol Bertoni"}]},{"@type":"WebSite","@id":"https:\/\/giflex.it\/#website","url":"https:\/\/giflex.it\/","name":"Giflex","description":"Italian Flexible Packaging Association","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/giflex.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/giflex.it\/#\/schema\/person\/9fda58bd92203f69ec32c836be0bd030","name":"Paolo Giovenzana","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca8be5121e6be0d735b4265cd82a7793bdedf1077a17d012562ca570684730fa?s=96&d=mm&r=g","caption":"Paolo Giovenzana"},"description":"prova","sameAs":["https:\/\/federazionecartagrafica.it"],"url":"https:\/\/giflex.it\/en\/author\/paologiove\/"}]}},"_links":{"self":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/12194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/comments?post=12194"}],"version-history":[{"count":2,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/12194\/revisions"}],"predecessor-version":[{"id":12223,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posts\/12194\/revisions\/12223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media\/12206"}],"wp:attachment":[{"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/media?parent=12194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/categories?post=12194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/tags?post=12194"},{"taxonomy":"fonte","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/fonte?post=12194"},{"taxonomy":"posizione","embeddable":true,"href":"https:\/\/giflex.it\/en\/wp-json\/wp\/v2\/posizione?post=12194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}